{"id":70,"count":20,"description":"","link":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/","name":"Oriental Collection Leaflets","slug":"orientalcollectionleaflets","taxonomy":"product_cat","parent":69,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oriental Collection Leaflets Archives - Serendipity<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oriental Collection Leaflets Archives - Serendipity\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/\" \/>\n<meta property=\"og:site_name\" content=\"Serendipity\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/leaflets\\\/orientalcollectionleaflets\\\/\",\"url\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/leaflets\\\/orientalcollectionleaflets\\\/\",\"name\":\"Oriental Collection Leaflets Archives - Serendipity\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/leaflets\\\/orientalcollectionleaflets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/leaflets\\\/orientalcollectionleaflets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serendipitydesigns.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serendipity Designs\",\"item\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leaflets\",\"item\":\"https:\\\/\\\/serendipitydesigns.com\\\/index.php\\\/product-category\\\/serendipitydesigns\\\/leaflets\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Oriental Collection Leaflets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#website\",\"url\":\"https:\\\/\\\/serendipitydesigns.com\\\/\",\"name\":\"Serendipity\",\"description\":\"Counted Cross Stitch of Distinction\",\"publisher\":{\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serendipitydesigns.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#organization\",\"name\":\"Serendipity\",\"url\":\"https:\\\/\\\/serendipitydesigns.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serendipitydesigns.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/sdlogo-teal.png\",\"contentUrl\":\"https:\\\/\\\/serendipitydesigns.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/sdlogo-teal.png\",\"width\":579,\"height\":85,\"caption\":\"Serendipity\"},\"image\":{\"@id\":\"https:\\\/\\\/serendipitydesigns.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oriental Collection Leaflets Archives - Serendipity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/","og_locale":"en_US","og_type":"article","og_title":"Oriental Collection Leaflets Archives - Serendipity","og_url":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/","og_site_name":"Serendipity","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/","url":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/","name":"Oriental Collection Leaflets Archives - Serendipity","isPartOf":{"@id":"https:\/\/serendipitydesigns.com\/#website"},"breadcrumb":{"@id":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/orientalcollectionleaflets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serendipitydesigns.com\/"},{"@type":"ListItem","position":2,"name":"Serendipity Designs","item":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/"},{"@type":"ListItem","position":3,"name":"Leaflets","item":"https:\/\/serendipitydesigns.com\/index.php\/product-category\/serendipitydesigns\/leaflets\/"},{"@type":"ListItem","position":4,"name":"Oriental Collection Leaflets"}]},{"@type":"WebSite","@id":"https:\/\/serendipitydesigns.com\/#website","url":"https:\/\/serendipitydesigns.com\/","name":"Serendipity","description":"Counted Cross Stitch of Distinction","publisher":{"@id":"https:\/\/serendipitydesigns.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serendipitydesigns.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/serendipitydesigns.com\/#organization","name":"Serendipity","url":"https:\/\/serendipitydesigns.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/serendipitydesigns.com\/#\/schema\/logo\/image\/","url":"https:\/\/serendipitydesigns.com\/wp-content\/uploads\/2025\/04\/sdlogo-teal.png","contentUrl":"https:\/\/serendipitydesigns.com\/wp-content\/uploads\/2025\/04\/sdlogo-teal.png","width":579,"height":85,"caption":"Serendipity"},"image":{"@id":"https:\/\/serendipitydesigns.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/serendipitydesigns.com\/index.php\/wp-json\/wp\/v2\/product_cat\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serendipitydesigns.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/serendipitydesigns.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/serendipitydesigns.com\/index.php\/wp-json\/wp\/v2\/product_cat\/69"}],"wp:post_type":[{"href":"https:\/\/serendipitydesigns.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}